{"id":29352,"date":"2025-10-06T23:13:33","date_gmt":"2025-10-06T23:13:33","guid":{"rendered":"https:\/\/electrolux.ge\/?post_type=product&#038;p=29352"},"modified":"2025-10-19T02:50:08","modified_gmt":"2025-10-19T02:50:08","slug":"electrolux-lod8p39z","status":"publish","type":"product","link":"https:\/\/electrolux.ge\/ka\/product\/electrolux-lod8p39z\/","title":{"rendered":"Electrolux LOD8P39Z"},"content":{"rendered":"<p><strong>For delicious baking, just add steam<\/strong><br \/>\nThe SteamBake multifunction oven uses steam for delicious baking&#8230;<\/p>\n<hr>\n<p><strong>\u10d2\u10d4\u10db\u10e0\u10d8\u10d4\u10da\u10d8 \u10e1\u10d0\u10ea\u10ee\u10dd\u10d1\u10d8 \u10db\u10ee\u10dd\u10da\u10dd\u10d3 \u10dd\u10e0\u10d7\u10e5\u10da\u10d8\u10d7<\/strong><br \/>\nSteamBake \u10db\u10e0\u10d0\u10d5\u10d0\u10da\u10e4\u10e3\u10dc\u10e5\u10ea\u10d8\u10e3\u10e0\u10d8 \u10e6\u10e3\u10db\u10d4\u10da\u10d8 \u10d8\u10e7\u10d4\u10dc\u10d4\u10d1\u10e1 \u10dd\u10e0\u10d7\u10e5\u10da\u10e1 \u10d2\u10d4\u10db\u10e0\u10d8\u10d4\u10da\u10d8 \u10e1\u10d0\u10ea\u10ee\u10dd\u10d1\u10d8\u10e1\u10d7\u10d5\u10d8\u10e1&#8230;<\/p>","protected":false},"excerpt":{"rendered":"<div class=\"product-specs\">\n<h3>\u10d3\u10d0\u10db\u10d0\u10e2\u10d4\u10d1\u10d8\u10d7\u10d8 \u10e1\u10de\u10d4\u10ea\u10d8\u10e4\u10d8\u10d9\u10d0\u10ea\u10d8\u10d0<\/h3>\n<table class=\"specs-table\" style=\"width:100%; border-collapse:collapse;\">\n<tbody>\n<tr>\n<th>\u10d1\u10e0\u10d4\u10dc\u10d3\u10d8<\/th>\n<td>\u10d4\u10da\u10e5\u10e2\u10e0\u10dd\u10da\u10e3\u10e5\u10e1\u10d8<\/td>\n<th>\u10db\u10dd\u10d3\u10d4\u10da\u10d8<\/th>\n<td>LOD8P39Z<\/td>\n<th>\u10e2\u10d8\u10de\u10d8<\/th>\n<td>\u10e6\u10e3\u10db\u10d4\u10da\u10d8<\/td>\n<\/tr>\n<tr>\n<th>\u10d9\u10dd\u10dc\u10e1\u10e2\u10e0\u10e3\u10e5\u10ea\u10d8\u10d0<\/th>\n<td>\u10e9\u10d0\u10e8\u10d4\u10dc\u10d4\u10d1\u10e3\u10da\u10d8<\/td>\n<th>\u10d6\u10dd\u10db\u10d4\u10d1\u10d8<\/th>\n<td>59.4 \u00d7 59.6 \u00d7 56.9 cm<\/td>\n<th>\u10d2\u10d0\u10e0\u10d4 \u10db\u10d0\u10e2\u10d4\u10e0\u10d8\u10d0\u10da\u10d8<\/th>\n<td>\u10e8\u10d0\u10d5\u10d8 \u10db\u10d8\u10dc\u10d0<\/td>\n<\/tr>\n<tr>\n<th>\u10d4\u10dc\u10d4\u10e0\u10d2\u10dd \u10d4\u10e4\u10d4\u10e5\u10e2\u10e3\u10e0\u10dd\u10d1\u10d0<\/th>\n<td>A+<\/td>\n<th>\u10e6\u10e3\u10db\u10d4\u10da\u10d8\u10e1 \u10db\u10dd\u10ea\u10e3\u10da\u10dd\u10d1\u10d0<\/th>\n<td>72 L<\/td>\n<th>\u10d7\u10d5\u10d8\u10d7\u10ec\u10db\u10d4\u10dc\u10d3\u10d8\u10e1 \u10e2\u10d8\u10de\u10d8<\/th>\n<td>\u10de\u10d8\u10e0\u10dd\u10da\u10d8\u10e2\u10e3\u10e0\u10d8 \u10ec\u10db\u10d4\u10dc\u10d3\u10d0<\/td>\n<\/tr>\n<tr>\n<th>\u10e2\u10d4\u10db\u10de\u10d4\u10e0\u10d0\u10e2\u10e3\u10e0\u10d8\u10e1 \u10d3\u10d8\u10d0\u10de\u10d0\u10d6\u10dd\u10dc\u10d8<\/th>\n<td>30\u00b0C \u2013 300\u00b0C<\/td>\n<th>\u10e8\u10d8\u10d3\u10d0 \u10e1\u10d0\u10e4\u10d0\u10e0\u10d8<\/th>\n<td>\u10d0\u10d3\u10d5\u10d8\u10da\u10d0\u10d3 \u10d2\u10d0\u10e1\u10d0\u10ec\u10db\u10d4\u10dc\u10d3\u10d8 \u10db\u10d8\u10dc\u10d0\u10dc\u10e5\u10d0\u10e0\u10d8<\/td>\n<th>\u10db\u10d0\u10e0\u10d7\u10d5\u10d8\u10e1 \u10e2\u10d8\u10de\u10d8<\/th>\n<td>\u10e8\u10d4\u10ee\u10d4\u10d1\u10d0<\/td>\n<\/tr>\n<tr>\n<th>\u10e4\u10e3\u10dc\u10e5\u10ea\u10d8\u10d4\u10d1\u10d8<\/th>\n<td colspan=\"5\">\n          \u2022 \u10e5\u10d5\u10d4\u10d3\u10d0 \u10d2\u10d0\u10d7\u10d1\u10dd\u10d1\u10d0<br \/>\n          \u2022 \u10d6\u10d4\u10d3\u10d0 + \u10e5\u10d5\u10d4\u10d3\u10d0 \u10d2\u10d0\u10d7\u10d1\u10dd\u10d1\u10d0<br \/>\n          \u10d2\u10d0\u10dc\u10d0\u10d7\u10d4\u10d1\u10d0<br \/>\n          \u10de\u10d8\u10ea\u10d0<br \/>\n          \u10d2\u10e0\u10d8\u10da\u10d8<br \/>\n          \u10e2\u10e3\u10e0\u10d1\u10dd \u10d2\u10e0\u10d8\u10da\u10d8<br \/>\n          \u10ea\u10ee\u10d4\u10da\u10d8 \u10f0\u10d0\u10d4\u10e0\u10d8\u10e1 \u10ea\u10d8\u10e0\u10d9\u10e3\u10da\u10d0\u10ea\u10d8\u10d0<br \/>\n          \u10d2\u10d0\u10da\u10e6\u10dd\u10d1\u10d0<br \/>\n          \u10de\u10d8\u10e0\u10dd\u10da\u10d8\u10e2\u10e3\u10e0\u10d8 \u10d7\u10d5\u10d8\u10d7\u10ec\u10db\u10d4\u10dc\u10d3\u10d0<br \/>\n          \u10dd\u10e0\u10d7\u10e5\u10da\u10d6\u10d4 \u10db\u10dd\u10db\u10d6\u10d0\u10d3\u10d4\u10d1\u10d0\n        <\/td>\n<\/tr>\n<tr>\n<th>\u10d3\u10d0\u10db\u10d0\u10e2\u10d4\u10d1\u10d8\u10d7\u10d8 \u10d0\u10e5\u10e1\u10d4\u10e1\u10e3\u10d0\u10e0\u10d4\u10d1\u10d8<\/th>\n<td colspan=\"5\">\n          \u2022 \u10e3\u10df\u10d0\u10dc\u10d2\u10d0\u10d5\u10d8 \u10e4\u10dd\u10da\u10d0\u10d3\u10d8\u10e1 \u10da\u10d0\u10dc\u10d2\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10db\u10ed\u10d4\u10e0\u10d4\u10d1\u10d8<br \/>\n          \u2022 \u10e2\u10d4\u10da\u10d4\u10e1\u10d9\u10dd\u10de\u10e3\u10e0\u10d8 \u10e0\u10d4\u10da\u10e1\u10e3\u10e0\u10d8 \u10e1\u10d8\u10e1\u10e2\u10d4\u10db\u10d0<br \/>\n          \u2022 \u10e6\u10e0\u10db\u10d0 \u10e1\u10d0\u10ea\u10ee\u10dd\u10d1\u10d8 \u10e4\u10dd\u10e0\u10db\u10d0<br \/>\n          \u2022 \u10db\u10d8\u10dc\u10d0\u10dc\u10e5\u10e0\u10d8\u10d7 \u10d3\u10d0\u10e4\u10d0\u10e0\u10e3\u10da\u10d8 \u10e1\u10d0\u10ea\u10ee\u10dd\u10d1\u10d8 \u10e4\u10dd\u10e0\u10db\u10d0<br \/>\n          \u2022 \u10d9\u10d0\u10d1\u10d4\u10da\u10d8\u10e1 \u10e1\u10d0\u10d7\u10d0\u10d5\u10e1\u10dd<br \/>\n          \u2022 \u10e1\u10d0\u10db\u10db\u10d0\u10d2\u10d8 \u10db\u10d8\u10dc\u10d8\u10e1 \u10d9\u10d0\u10e0\u10d8<br \/>\n          \u10e2\u10d4\u10db\u10de\u10d4\u10e0\u10d0\u10e2\u10e3\u10e0\u10d8\u10e1 \u10e1\u10d4\u10dc\u10e1\u10dd\u10e0\u10d8 (\u10d7\u10d4\u10e0\u10db\u10dd\u10e1\u10d4\u10dc\u10e1\u10dd\u10e0\u10d8)\n        <\/td>\n<\/tr>\n<tr>\n<th>\u10d3\u10d0\u10db\u10d0\u10e2\u10d4\u10d1\u10d8\u10d7\u10d8 \u10e4\u10e3\u10dc\u10e5\u10ea\u10d8\u10dd\u10dc\u10d0\u10da\u10d8<\/th>\n<td colspan=\"5\">\n          \u10d0\u10d9\u10e3\u10e1\u10e2\u10d8\u10d9\u10e3\u10e0\u10d8 \u10e2\u10d0\u10d8\u10db\u10d4\u10e0\u10d8<br \/>\n          \u10d9\u10d0\u10e0\u10d8\u10e1 \u10db\u10e1\u10e3\u10d1\u10e3\u10d0\u10d3 \u10d2\u10d0\u10e6\u10d4\u10d1\u10d0<br \/>\n          \u10d9\u10d0\u10e0\u10d8\u10e1 \u10db\u10e1\u10e3\u10d1\u10e3\u10e5\u10d0\u10d3 \u10d3\u10d0\u10ee\u10e3\u10e0\u10d5\u10d0<br \/>\n          \u10f0\u10d0\u10da\u10dd\u10d2\u10d4\u10dc\u10e3\u10e0\u10d8 \u10d2\u10d0\u10dc\u10d0\u10d7\u10d4\u10d1\u10d0<br \/>\n          \u10e1\u10d4\u10dc\u10e1\u10dd\u10e0\u10e3\u10da\u10d8 \u10db\u10d0\u10e0\u10d7\u10d5\u10d8\u10e1 \u10de\u10d0\u10dc\u10d4\u10da\u10d8<br \/>\n          \u10d0\u10e3\u10e2\u10dd \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d0<br \/>\n          \u10e4\u10d0\u10d5\u10dd\u10e0\u10d8\u10e2\u10d8 \u10de\u10e0\u10dd\u10d2\u10e0\u10d0\u10db\u10d4\u10d1\u10d8<br \/>\n          \u10e2\u10d4\u10db\u10de\u10d4\u10e0\u10d0\u10e2\u10e3\u10e0\u10d8\u10e1 \u10d0\u10d5\u10e2\u10dd\u10db\u10d0\u10e2\u10e3\u10e0\u10d8 \u10e8\u10d4\u10d7\u10d0\u10d5\u10d0\u10d6\u10d4\u10d1\u10d0<br \/>\n          \u10ec\u10d8\u10dc\u10d0\u10e1\u10ec\u10d0\u10e0\u10d8 \u10d2\u10d0\u10ea\u10ee\u10d4\u10da\u10d4\u10d1\u10d0<br \/>\n          \u10e1\u10d0\u10db\u10d3\u10dd\u10dc\u10d8\u10d0\u10dc\u10d8 \u10db\u10dd\u10db\u10d6\u10d0\u10d3\u10d4\u10d1\u10d0<br \/>\n          \u10d2\u10d0\u10db\u10dd\u10ea\u10ee\u10dd\u10d1\u10d8\u10e1 \u10e4\u10e3\u10dc\u10e5\u10ea\u10d8\u10d0<br \/>\n          \u10ea\u10dd\u10db\u10d8\u10e1 \u10d0\u10db\u10dd\u10e7\u10d5\u10d0\u10dc\u10d8\u10e1 \u10e0\u10d4\u10df\u10d8\u10db\u10d8\n        <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>","protected":false},"featured_media":29356,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[76],"product_cat":[82],"product_tag":[],"class_list":{"0":"post-29352","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-electrolux","7":"product_cat-oven","9":"first","10":"instock","11":"virtual","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/product\/29352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/comments?post=29352"}],"version-history":[{"count":4,"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/product\/29352\/revisions"}],"predecessor-version":[{"id":29600,"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/product\/29352\/revisions\/29600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/media\/29356"}],"wp:attachment":[{"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/media?parent=29352"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/product_brand?post=29352"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/product_cat?post=29352"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/electrolux.ge\/ka\/wp-json\/wp\/v2\/product_tag?post=29352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}